{"id":125,"count":0,"description":"","link":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/","name":"Sustainable employability","slug":"sustainable-employability","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sustainable employability Archieven - HC Health<\/title>\n<meta name=\"description\" content=\"Sustainable employability Archieven - HC Health\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sustainable employability Archieven\" \/>\n<meta property=\"og:description\" content=\"Sustainable employability Archieven - HC Health\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/\" \/>\n<meta property=\"og:site_name\" content=\"HC Health\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hchealth.nl\\\/en\\\/category\\\/sustainable-employability\\\/\",\"url\":\"https:\\\/\\\/hchealth.nl\\\/en\\\/category\\\/sustainable-employability\\\/\",\"name\":\"Sustainable employability Archieven - HC Health\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#website\"},\"description\":\"Sustainable employability Archieven - HC Health\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hchealth.nl\\\/en\\\/category\\\/sustainable-employability\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hchealth.nl\\\/en\\\/category\\\/sustainable-employability\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hchealth.nl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sustainable employability\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#website\",\"url\":\"https:\\\/\\\/hchealth.nl\\\/\",\"name\":\"HC Health\",\"description\":\"Vitaliteitsmanagement | Duurzame Inzetbaarheid\",\"publisher\":{\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hchealth.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#organization\",\"name\":\"HC Health\",\"url\":\"https:\\\/\\\/hchealth.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hchealth.nl\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-HC-Health.svg\",\"contentUrl\":\"https:\\\/\\\/hchealth.nl\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-HC-Health.svg\",\"width\":960,\"height\":960,\"caption\":\"HC Health\"},\"image\":{\"@id\":\"https:\\\/\\\/hchealth.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sustainable employability Archieven - HC Health","description":"Sustainable employability Archieven - HC Health","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Sustainable employability Archieven","og_description":"Sustainable employability Archieven - HC Health","og_url":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/","og_site_name":"HC Health","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/","url":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/","name":"Sustainable employability Archieven - HC Health","isPartOf":{"@id":"https:\/\/hchealth.nl\/#website"},"description":"Sustainable employability Archieven - HC Health","breadcrumb":{"@id":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hchealth.nl\/en\/category\/sustainable-employability\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hchealth.nl\/en\/"},{"@type":"ListItem","position":2,"name":"Sustainable employability"}]},{"@type":"WebSite","@id":"https:\/\/hchealth.nl\/#website","url":"https:\/\/hchealth.nl\/","name":"HC Health","description":"Vitaliteitsmanagement | Duurzame Inzetbaarheid","publisher":{"@id":"https:\/\/hchealth.nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hchealth.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hchealth.nl\/#organization","name":"HC Health","url":"https:\/\/hchealth.nl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hchealth.nl\/#\/schema\/logo\/image\/","url":"https:\/\/hchealth.nl\/wp-content\/uploads\/2021\/09\/Logo-HC-Health.svg","contentUrl":"https:\/\/hchealth.nl\/wp-content\/uploads\/2021\/09\/Logo-HC-Health.svg","width":960,"height":960,"caption":"HC Health"},"image":{"@id":"https:\/\/hchealth.nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hchealth.nl\/en\/wp-json\/wp\/v2\/categories\/125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hchealth.nl\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hchealth.nl\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hchealth.nl\/en\/wp-json\/wp\/v2\/posts?categories=125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}